{"id":22759,"date":"2021-06-16T16:49:00","date_gmt":"2021-06-16T16:49:00","guid":{"rendered":"https:\/\/www.tyman-international.com\/nuevo-catalogo-tecnico-general-giesse\/"},"modified":"2026-05-22T12:34:34","modified_gmt":"2026-05-22T12:34:34","slug":"nuevo-catalogo-tecnico-general-giesse","status":"publish","type":"post","link":"https:\/\/www.tyman-international.com\/es\/noticias-eventos\/nuevo-catalogo-tecnico-general-giesse\/","title":{"rendered":"Nuevo cat\u00e1logo t\u00e9cnico general Giesse"},"content":{"rendered":"\n<p>La bisagra para puertas <strong>El cat\u00e1logo t\u00e9cnico general Giesse<\/strong> (<strong>GTC<\/strong>) est\u00e1 de vuelta con m\u00e1s de <strong>688 p\u00e1ginas<\/strong> y <strong>1500 productos<\/strong>. La primera y principal fuente de informaci\u00f3n t\u00e9cnica del vasto universo de productos <a href=\"https:\/\/www.tyman-international.com\/es\/empresa\/quienes-somos\/giesse-herrajes-para-puertas-y-ventanas-de-aluminio\/\">Giesse<\/a>.<\/p>\n\n\n\n<p>Descubra la amplia gama de herrajes para puertas y ventanas de aluminio. El cat\u00e1logo est\u00e1 disponible en <strong>7 idiomas<\/strong>: ingl\u00e9s, italiano, espa\u00f1ol, alem\u00e1n, franc\u00e9s, portugu\u00e9s, ruso.<\/p>\n\n\n\n<div class=\"link\"><a class=\"btn\" href=\"https:\/\/www.tyman-international.com\/es\/asistencia\/descargar\/?c%5B0%5D%5B%5D=&amp;c%5B1%5D%5B%5D=&amp;c%5B2%5D%5B%5D=&amp;t=GTC\">Descargar el cat\u00e1logo t\u00e9cnico general<\/a><\/div>\n\n\n\n<p><\/p>\n\n\n<div class=\"epyt-video-wrapper\"><iframe  id=\"_ytid_59712\"  width=\"800\" height=\"450\"  data-origwidth=\"800\" data-origheight=\"450\"  data-relstop=\"1\" src=\"https:\/\/www.youtube.com\/embed\/jhFf9XGvvvI?enablejsapi=1&autoplay=0&cc_load_policy=1&cc_lang_pref=&iv_load_policy=3&loop=0&rel=0&fs=1&playsinline=0&autohide=2&theme=dark&color=red&controls=1&disablekb=0&\" class=\"__youtube_prefs__  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p>El <strong>cat\u00e1logo general de Giesse<\/strong> incluye los siguientes <strong>cap\u00edtulos<\/strong>:<\/p>\n\n\n\n<p class=\"has-text-align-left\"><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Bisagras para puertas y ventanas<\/li>\n\n\n\n<li>Mecanismos y herrajes de cierre<\/li>\n\n\n\n<li>Juntas y componentes de los mecanismos de cierre<\/li>\n\n\n\n<li>Tapones, compensadores y escuadras<\/li>\n\n\n\n<li>Sistema completo para la maniobra y el cierre<\/li>\n\n\n\n<li>Mecanismos y kits para ventanas oscilo batientes<\/li>\n\n\n\n<li>Accesorios y herrajes de cierre para correderas<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>De lo anal\u00f3gico a lo digital: todas las p\u00e1ginas tienen un <strong>c\u00f3digo QR<\/strong> para acceder al cat\u00e1logo digital. Escan\u00e9elo para navegar f\u00e1cilmente entre <strong>los detalles de los productos<\/strong>, <strong>v\u00eddeos<\/strong>, <strong>fichas t\u00e9cnicas<\/strong>, <strong>archivos CAD<\/strong> y dem\u00e1s documentos pertinentes.<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><img fetchpriority=\"high\" decoding=\"async\" width=\"400\" height=\"225\" class=\"wp-image-11663\" style=\"width: 400px;\" src=\"https:\/\/www.tyman-international.com\/wp-content\/uploads\/2021\/06\/GTC-qr-code-1.gif\" alt=\"\"><\/td><td class=\"has-text-align-center\" data-align=\"center\"><img decoding=\"async\" width=\"400\" height=\"225\" class=\"wp-image-11627\" style=\"width: 400px;\" src=\"https:\/\/www.tyman-international.com\/wp-content\/uploads\/2021\/06\/GTC-qr-code.gif\" alt=\"giesse-digital-catalogue-documents\"><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Paso 1<\/strong>: Escanee el c\u00f3digo QR<\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Paso 2<\/strong>: Encuentre los documentos en el \u00e1rea de descargas <\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p><\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<p>Encontrar\u00e1 m\u00e1s productos Giesse en los siguientes documentos:<\/p>\n\n\n\n<p><strong>Cat\u00e1logo de aberturas especiales Giesse<\/strong>. Incluye todas las soluciones GS1000 y GS3000. <br><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.tyman-international.com\/es\/soluciones\/lineas-de-producto\/?solution=2908#ss\">GS 1000<\/a><\/strong>: sistema de herrajes para oscilo correderas con control forzado manual o semiautom\u00e1tico para realizar hojas de hasta 200 kg. Para aplicaciones con hojas de hasta 200 kg.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/www.tyman-international.com\/es\/soluciones\/lineas-de-producto\/?solution=2908#ss\">GS 3000<\/a><\/strong>: sistema de herrajes para correderas elevables para realizar hojas de hasta 400 kg.<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"link\"><a class=\"btn\" href=\"https:\/\/www.tyman-international.com\/es\/asistencia\/descargar-catalogos-folletos\/?c%5B0%5D%5B%5D=&#038;c%5B1%5D%5B%5D=2886&#038;c%5B2%5D%5B%5D=&#038;t=GTC\">Descargar el cat\u00e1logo de aberturas especiales<\/a><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Cat\u00e1logo de automatismos de Giesse<\/strong>. Incluye <strong>actuadores de cadena<\/strong>, <strong>actuadores de varilla<\/strong>, <strong>actuadores de cremallera<\/strong> para sistemas de ventilaci\u00f3n antural o extracci\u00f3n de humo y calor (sistemas RWA).<\/p>\n\n\n\n<div class=\"link\"><a class=\"btn\" href=\"https:\/\/www.tyman-international.com\/es\/asistencia\/descargar-catalogos-folletos\/?c%5B0%5D%5B%5D=&#038;c%5B1%5D%5B%5D=2886&#038;c%5B2%5D%5B%5D=&#038;t=AUTO\">Descargar cat\u00e1logo de automatismos<\/a><\/div>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<p><\/p>\n\n\n\n<p>P\u00f3ngase en contacto con nosotros para recibir informaci\u00f3n adicional<\/p>\n\n\n\n<div class=\"link\"><a class=\"btn\" href=\"https:\/\/www.tyman-international.com\/es\/asistencia\/contactos\/\">Cont\u00e1ctenos<\/a><\/div>\n\n\n\n<p><\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Cada p\u00e1gina incluye enlaces de c\u00f3digo QR al cat\u00e1logo digital para conocer todos los detalles del producto.<\/p>\n","protected":false},"author":4,"featured_media":19968,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2886,2885,2884],"tags":[],"class_list":["post-22759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-giesse-es","category-noticias-eventos","category-productos"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.tyman-international.com\/es\/wp-json\/wp\/v2\/posts\/22759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tyman-international.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tyman-international.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tyman-international.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tyman-international.com\/es\/wp-json\/wp\/v2\/comments?post=22759"}],"version-history":[{"count":1,"href":"https:\/\/www.tyman-international.com\/es\/wp-json\/wp\/v2\/posts\/22759\/revisions"}],"predecessor-version":[{"id":55977,"href":"https:\/\/www.tyman-international.com\/es\/wp-json\/wp\/v2\/posts\/22759\/revisions\/55977"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tyman-international.com\/es\/wp-json\/wp\/v2\/media\/19968"}],"wp:attachment":[{"href":"https:\/\/www.tyman-international.com\/es\/wp-json\/wp\/v2\/media?parent=22759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tyman-international.com\/es\/wp-json\/wp\/v2\/categories?post=22759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tyman-international.com\/es\/wp-json\/wp\/v2\/tags?post=22759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}